{"id":5033,"date":"2024-11-06T14:38:34","date_gmt":"2024-11-06T14:38:34","guid":{"rendered":"https:\/\/bellasartes.edu.py\/?p=5033"},"modified":"2024-11-06T15:05:43","modified_gmt":"2024-11-06T15:05:43","slug":"escuela-de-danza","status":"publish","type":"post","link":"https:\/\/bellasartes.edu.py\/index.php\/2024\/11\/06\/escuela-de-danza\/","title":{"rendered":"Festival de Clausura del a\u00f1o lectivo de la Escuela de Danza de Bellas Artes"},"content":{"rendered":"\n<p>Con una imponente puesta en escena, La Escuela de Danza del Instituto Superior de Bellas Artes, bajo la Direcci\u00f3n del Centro Experimental para el Desarrollo de las Artes, conmemor\u00f3 sus 65 a\u00f1os de trayectoria. La presentaci\u00f3n se realizar\u00e1 en el teatro \u201cAgust\u00edn P\u00edo Barrios\u201d del Centro Paraguayo Japon\u00e9s, el 30 de octubre a las 19:30 h, con la participaci\u00f3n de todo el cuerpo de alumnos de la Escuela de Danza. .\u00a0<\/p>\n\n\n\n<p>En la ocasi\u00f3n, la Escuela ofreci\u00f3 un espect\u00e1culo presentando las obras coreogr\u00e1ficas \u201cCeremonia de Graduaci\u00f3n\u201d (Danza cl\u00e1sica), un divertimento que narra los sucesos de una fiesta de graduaci\u00f3n en una Escuela de se\u00f1oritas, donde desborda la alegr\u00eda de danzar y \u201cDanzando entre los pentagramas de mi tierra\u201d (Danza contempor\u00e1nea), que se trata de un cuadro coreogr\u00e1fico que celebra la identidad paraguaya y la rica herencia cultural musical de Paraguay a trav\u00e9s de la danza contempor\u00e1nea y la fusi\u00f3n vibrante de g\u00e9neros como las Avanzadas y las Guaranias, una invitaci\u00f3n a sumergirse en sus tradiciones musicales bajo la mirada innovadora de la danza contempor\u00e1nea. .&nbsp;<\/p>\n\n\n\n<p>En \u201cCeremonia de Graduaci\u00f3n\u201d se cont\u00f3 con la actuaci\u00f3n especial de profesores de la carrera de Teatro del ISBA, Roxana Lescano y Evert Capdevila y como invitados los cadetes de la Academia Nacional de Polic\u00eda Gral. Jos\u00e9 E. D\u00edaz.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Festival de Clausura de la Escuela de Danza del CEDARTS 2024\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/8Gspuw_5Qv4?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Con una imponente puesta en escena, La Escuela de Danza del Instituto Superior de Bellas Artes, bajo la Direcci\u00f3n del Centro Experimental para el Desarrollo de las Artes, conmemor\u00f3 sus 65 a\u00f1os de trayectoria. La presentaci\u00f3n se realizar\u00e1 en el teatro \u201cAgust\u00edn P\u00edo Barrios\u201d del Centro Paraguayo Japon\u00e9s, el 30 de octubre a las 19:30 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5034,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"fifu_image_url":"","fifu_image_alt":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-5033","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Escuela de Danza<\/title>\n<meta name=\"description\" content=\"La Escuela de Danza de Bellas Artes, bajo la Direcci\u00f3n del Centro Experimental para el Desarrollo de las Artes, conmemor\u00f3 sus 65 a\u00f1os.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bellasartes.edu.py\/index.php\/2024\/11\/06\/escuela-de-danza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Escuela de Danza\" \/>\n<meta property=\"og:description\" content=\"La Escuela de Danza de Bellas Artes, bajo la Direcci\u00f3n del Centro Experimental para el Desarrollo de las Artes, conmemor\u00f3 sus 65 a\u00f1os.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bellasartes.edu.py\/index.php\/2024\/11\/06\/escuela-de-danza\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto Superior de Bellas Artes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/isbaoficial\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-06T14:38:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-06T15:05:43+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/bellasartes.edu.py\/wp-content\/uploads\/2024\/11\/DSC00062-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1439\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicarte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicarte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2024\\\/11\\\/06\\\/escuela-de-danza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2024\\\/11\\\/06\\\/escuela-de-danza\\\/\"},\"author\":{\"name\":\"comunicarte\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#\\\/schema\\\/person\\\/6243d56ea2e518f0b57594d7a454e37a\"},\"headline\":\"Festival de Clausura del a\u00f1o lectivo de la Escuela de Danza de Bellas Artes\",\"datePublished\":\"2024-11-06T14:38:34+00:00\",\"dateModified\":\"2024-11-06T15:05:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2024\\\/11\\\/06\\\/escuela-de-danza\\\/\"},\"wordCount\":263,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2024\\\/11\\\/06\\\/escuela-de-danza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bellasartes.edu.py\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/DSC00062-scaled.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2024\\\/11\\\/06\\\/escuela-de-danza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2024\\\/11\\\/06\\\/escuela-de-danza\\\/\",\"url\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2024\\\/11\\\/06\\\/escuela-de-danza\\\/\",\"name\":\"Escuela de Danza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2024\\\/11\\\/06\\\/escuela-de-danza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2024\\\/11\\\/06\\\/escuela-de-danza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bellasartes.edu.py\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/DSC00062-scaled.jpg\",\"datePublished\":\"2024-11-06T14:38:34+00:00\",\"dateModified\":\"2024-11-06T15:05:43+00:00\",\"description\":\"La Escuela de Danza de Bellas Artes, bajo la Direcci\u00f3n del Centro Experimental para el Desarrollo de las Artes, conmemor\u00f3 sus 65 a\u00f1os.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2024\\\/11\\\/06\\\/escuela-de-danza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2024\\\/11\\\/06\\\/escuela-de-danza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2024\\\/11\\\/06\\\/escuela-de-danza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bellasartes.edu.py\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/DSC00062-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/bellasartes.edu.py\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/DSC00062-scaled.jpg\",\"width\":2560,\"height\":1439},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2024\\\/11\\\/06\\\/escuela-de-danza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bellasartes.edu.py\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festival de Clausura del a\u00f1o lectivo de la Escuela de Danza de Bellas Artes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#website\",\"url\":\"https:\\\/\\\/bellasartes.edu.py\\\/\",\"name\":\"Instituto Superior de Bellas Artes\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bellasartes.edu.py\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#organization\",\"name\":\"Instituto Superior de Bellas Artes\",\"url\":\"https:\\\/\\\/bellasartes.edu.py\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bellasartes.edu.py\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-imagenes-y-logos_Mesa-de-trabajo-1.png\",\"contentUrl\":\"https:\\\/\\\/bellasartes.edu.py\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-imagenes-y-logos_Mesa-de-trabajo-1.png\",\"width\":512,\"height\":512,\"caption\":\"Instituto Superior de Bellas Artes\"},\"image\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/isbaoficial\",\"https:\\\/\\\/www.instagram.com\\\/bellasartes.py\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/74351323\\\/admin\\\/feed\\\/posts\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#\\\/schema\\\/person\\\/6243d56ea2e518f0b57594d7a454e37a\",\"name\":\"comunicarte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73b4d6769843e544de958c36b6a5ccd5fbfbe514a048340133a4d304a2f5777b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73b4d6769843e544de958c36b6a5ccd5fbfbe514a048340133a4d304a2f5777b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73b4d6769843e544de958c36b6a5ccd5fbfbe514a048340133a4d304a2f5777b?s=96&d=mm&r=g\",\"caption\":\"comunicarte\"},\"url\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/author\\\/comunicarte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Escuela de Danza","description":"La Escuela de Danza de Bellas Artes, bajo la Direcci\u00f3n del Centro Experimental para el Desarrollo de las Artes, conmemor\u00f3 sus 65 a\u00f1os.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bellasartes.edu.py\/index.php\/2024\/11\/06\/escuela-de-danza\/","og_locale":"es_ES","og_type":"article","og_title":"Escuela de Danza","og_description":"La Escuela de Danza de Bellas Artes, bajo la Direcci\u00f3n del Centro Experimental para el Desarrollo de las Artes, conmemor\u00f3 sus 65 a\u00f1os.","og_url":"https:\/\/bellasartes.edu.py\/index.php\/2024\/11\/06\/escuela-de-danza\/","og_site_name":"Instituto Superior de Bellas Artes","article_publisher":"https:\/\/www.facebook.com\/isbaoficial","article_published_time":"2024-11-06T14:38:34+00:00","article_modified_time":"2024-11-06T15:05:43+00:00","og_image":[{"width":2560,"height":1439,"url":"http:\/\/bellasartes.edu.py\/wp-content\/uploads\/2024\/11\/DSC00062-scaled.jpg","type":"image\/jpeg"}],"author":"comunicarte","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"comunicarte","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bellasartes.edu.py\/index.php\/2024\/11\/06\/escuela-de-danza\/#article","isPartOf":{"@id":"https:\/\/bellasartes.edu.py\/index.php\/2024\/11\/06\/escuela-de-danza\/"},"author":{"name":"comunicarte","@id":"https:\/\/bellasartes.edu.py\/#\/schema\/person\/6243d56ea2e518f0b57594d7a454e37a"},"headline":"Festival de Clausura del a\u00f1o lectivo de la Escuela de Danza de Bellas Artes","datePublished":"2024-11-06T14:38:34+00:00","dateModified":"2024-11-06T15:05:43+00:00","mainEntityOfPage":{"@id":"https:\/\/bellasartes.edu.py\/index.php\/2024\/11\/06\/escuela-de-danza\/"},"wordCount":263,"commentCount":0,"publisher":{"@id":"https:\/\/bellasartes.edu.py\/#organization"},"image":{"@id":"https:\/\/bellasartes.edu.py\/index.php\/2024\/11\/06\/escuela-de-danza\/#primaryimage"},"thumbnailUrl":"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2024\/11\/DSC00062-scaled.jpg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bellasartes.edu.py\/index.php\/2024\/11\/06\/escuela-de-danza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bellasartes.edu.py\/index.php\/2024\/11\/06\/escuela-de-danza\/","url":"https:\/\/bellasartes.edu.py\/index.php\/2024\/11\/06\/escuela-de-danza\/","name":"Escuela de Danza","isPartOf":{"@id":"https:\/\/bellasartes.edu.py\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bellasartes.edu.py\/index.php\/2024\/11\/06\/escuela-de-danza\/#primaryimage"},"image":{"@id":"https:\/\/bellasartes.edu.py\/index.php\/2024\/11\/06\/escuela-de-danza\/#primaryimage"},"thumbnailUrl":"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2024\/11\/DSC00062-scaled.jpg","datePublished":"2024-11-06T14:38:34+00:00","dateModified":"2024-11-06T15:05:43+00:00","description":"La Escuela de Danza de Bellas Artes, bajo la Direcci\u00f3n del Centro Experimental para el Desarrollo de las Artes, conmemor\u00f3 sus 65 a\u00f1os.","breadcrumb":{"@id":"https:\/\/bellasartes.edu.py\/index.php\/2024\/11\/06\/escuela-de-danza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bellasartes.edu.py\/index.php\/2024\/11\/06\/escuela-de-danza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bellasartes.edu.py\/index.php\/2024\/11\/06\/escuela-de-danza\/#primaryimage","url":"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2024\/11\/DSC00062-scaled.jpg","contentUrl":"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2024\/11\/DSC00062-scaled.jpg","width":2560,"height":1439},{"@type":"BreadcrumbList","@id":"https:\/\/bellasartes.edu.py\/index.php\/2024\/11\/06\/escuela-de-danza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bellasartes.edu.py\/"},{"@type":"ListItem","position":2,"name":"Festival de Clausura del a\u00f1o lectivo de la Escuela de Danza de Bellas Artes"}]},{"@type":"WebSite","@id":"https:\/\/bellasartes.edu.py\/#website","url":"https:\/\/bellasartes.edu.py\/","name":"Instituto Superior de Bellas Artes","description":"","publisher":{"@id":"https:\/\/bellasartes.edu.py\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bellasartes.edu.py\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/bellasartes.edu.py\/#organization","name":"Instituto Superior de Bellas Artes","url":"https:\/\/bellasartes.edu.py\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bellasartes.edu.py\/#\/schema\/logo\/image\/","url":"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2024\/03\/cropped-imagenes-y-logos_Mesa-de-trabajo-1.png","contentUrl":"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2024\/03\/cropped-imagenes-y-logos_Mesa-de-trabajo-1.png","width":512,"height":512,"caption":"Instituto Superior de Bellas Artes"},"image":{"@id":"https:\/\/bellasartes.edu.py\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/isbaoficial","https:\/\/www.instagram.com\/bellasartes.py\/","https:\/\/www.linkedin.com\/school\/74351323\/admin\/feed\/posts\/"]},{"@type":"Person","@id":"https:\/\/bellasartes.edu.py\/#\/schema\/person\/6243d56ea2e518f0b57594d7a454e37a","name":"comunicarte","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/73b4d6769843e544de958c36b6a5ccd5fbfbe514a048340133a4d304a2f5777b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/73b4d6769843e544de958c36b6a5ccd5fbfbe514a048340133a4d304a2f5777b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/73b4d6769843e544de958c36b6a5ccd5fbfbe514a048340133a4d304a2f5777b?s=96&d=mm&r=g","caption":"comunicarte"},"url":"https:\/\/bellasartes.edu.py\/index.php\/author\/comunicarte\/"}]}},"jetpack_featured_media_url":"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2024\/11\/DSC00062-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/posts\/5033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/comments?post=5033"}],"version-history":[{"count":2,"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/posts\/5033\/revisions"}],"predecessor-version":[{"id":5042,"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/posts\/5033\/revisions\/5042"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/media\/5034"}],"wp:attachment":[{"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/media?parent=5033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/categories?post=5033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/tags?post=5033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}