{"id":5892,"date":"2025-11-07T12:25:29","date_gmt":"2025-11-07T12:25:29","guid":{"rendered":"https:\/\/bellasartes.edu.py\/?p=5892"},"modified":"2025-11-07T12:25:33","modified_gmt":"2025-11-07T12:25:33","slug":"taller-de-la-hermandad","status":"publish","type":"post","link":"https:\/\/bellasartes.edu.py\/index.php\/2025\/11\/07\/taller-de-la-hermandad\/","title":{"rendered":"Taller de la Hermandad: una artesan\u00eda textil con historia que Bellas Artes desea intervenir"},"content":{"rendered":"\n<p><em>Entre hilos, retazos de tejidos y recuerdos, un grupo de mujeres de Santa Mar\u00eda de Fe, departamento de Misiones, mantiene viva una tradici\u00f3n artesanal nacida hace m\u00e1s de cuatro d\u00e9cadas. En el Taller de la Hermandad las artesanas bordan sus historias y realidades, con coloridas figuras hechas con retazos de tela, que forman personajes y escenarios propios del campo misionero.<\/em><\/p>\n\n\n\n<p><strong>Las primeras puntadas de una larga historia de arte<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"5894\" src=\"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0392-1024x683.jpg\" alt=\"\" class=\"wp-image-5894\" srcset=\"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0392-980x653.jpg 980w, https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0392-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"5896\" src=\"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0386-1024x683.jpg\" alt=\"\" class=\"wp-image-5896\" srcset=\"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0386-980x653.jpg 980w, https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0386-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"5895\" src=\"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0376-1024x683.jpg\" alt=\"\" class=\"wp-image-5895\" srcset=\"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0376-980x653.jpg 980w, https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0376-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n<\/figure>\n\n\n\n<p><em>\u201cHace unos cuarenta a\u00f1os y algo que trabajo en la artesan\u00eda\u201d<\/em>, recuerda Jer\u00f3nima, una de las integrantes m\u00e1s antiguas del grupo.<\/p>\n\n\n\n<p>La historia de las artesanas del Taller de la Hermandad comenz\u00f3 hace 45 a\u00f1os, guiadas por hermanas religiosas espa\u00f1olas: Ana, Tere y Mar\u00eda; quienes, en vista de la falta de oportunidades laborales para las mujeres del lugar, les ense\u00f1aron t\u00e9cnicas de costura, bordado y apliques sobre telas. <em>\u201cAntes ac\u00e1 no hab\u00eda trabajo. \u00c9ramos nuevitas y empez\u00e1bamos a trabajar\u201d<\/em>, cuenta una de ellas.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><a><\/a><strong>Lo que cuentan a trav\u00e9s del oficio<\/strong><\/h4>\n\n\n\n<p>Las artesan\u00edas del taller no son como cualquier otra: poseen un encanto especial. Son piezas textiles \u00fanicas que confeccionan una narrativa; cada dise\u00f1o cuenta algo de su propia vida cotidiana.<em> \u201cNuestros trabajos son nuestra identidad, nuestra realidad, lo que nosotras pasamos\u201d<\/em>, explican.<\/p>\n\n\n\n<p>&nbsp;Los bordados, que ornamentan cartucheras, remeras, manteles y llaveros, relatan escenas de la vida campesina: mujeres trayendo agua del pozo, lavando en el arroyo, yendo a la chacra, criando animales. En esas im\u00e1genes simples se conserva la memoria del trabajo femenino y de una forma de vida comunitaria.<\/p>\n\n\n\n<p><em>\u201cTra\u00edamos agua del arroyo, lav\u00e1bamos la ropa ah\u00ed, y eso bordamos. Esa es nuestra identidad de campesinas.\u201d<\/em><\/p>\n\n\n\n<p><strong>La resistencia de las artesanas frente a la crisis<\/strong><\/p>\n\n\n\n<p>A lo largo de los a\u00f1os, el grupo enfrent\u00f3 momentos dif\u00edciles. En una ocasi\u00f3n, perdieron el local donde trabajaban debido a problemas econ\u00f3micos y legales.<br><em>&nbsp;\u201cNos desalojaron. Llevaron las pocas cosas que ten\u00edamos&#8230; y nos lleg\u00f3 una demanda judicial. Nos amenazaron que \u00edbamos a ir al Buen Pastor\u201d<\/em>, recuerdan con tristeza.<\/p>\n\n\n\n<p>Lejos de rendirse, las mujeres se unieron, se manifestaron y encontraron ayuda en la comunidad, as\u00ed lograron recuperar sus herramientas y volver a empezar. <em>\u201cNos ca\u00edmos y nos volvimos a levantar.\u201d<\/em><\/p>\n\n\n\n<p>Con el tiempo, una benefactora inglesa llamada Margaret, las ayud\u00f3 a establecerse en un nuevo espacio. Desde entonces, hace m\u00e1s de veinte a\u00f1os, el grupo sigue trabajando en su taller actual, hoy integrado por doce mujeres que contin\u00faan la tradici\u00f3n iniciada por sus madres y abuelas.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><a><\/a><strong>Una tradici\u00f3n en riesgo de extinci\u00f3n<\/strong><\/h4>\n\n\n\n<p>De las mujeres pioneras, que se iniciaron en el trabajo artesanal con las hermanas, son tres las que a\u00fan permanecen: Jer\u00f3nima, Yolanda y Claudia. Las dem\u00e1s fueron incorpor\u00e1ndose al taller por el camino, hasta llegar a conformar 35 trabajadoras; m\u00e1s tarde, fueron retir\u00e1ndose de a poco.<\/p>\n\n\n\n<p>Hoy, la producci\u00f3n de su artesan\u00eda se est\u00e1 menguando cada vez m\u00e1s, con el cambio de rubro de las herederas de este saber, que abandonaron la pr\u00e1ctica tras haber concluido sus estudios. Con cada vez menos artesanas y baja rentabilidad, este arte podr\u00eda perderse.<\/p>\n\n\n\n<p><strong>Un proyecto de innovaci\u00f3n y dise\u00f1o de artesan\u00eda<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"5899\" src=\"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0367-1024x683.jpg\" alt=\"\" class=\"wp-image-5899\" srcset=\"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0367-980x653.jpg 980w, https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0367-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"5897\" src=\"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0402-1024x683.jpg\" alt=\"\" class=\"wp-image-5897\" srcset=\"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0402-980x653.jpg 980w, https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0402-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"5898\" src=\"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0374-1024x683.jpg\" alt=\"\" class=\"wp-image-5898\" srcset=\"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0374-980x653.jpg 980w, https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0374-480x320.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Por eso, la Direcci\u00f3n de Investigaci\u00f3n y Postgrado del ISBA y la profesora Leticia Cardozo, est\u00e1n encabezando un proyecto con el Taller de la Hermandad para la conservaci\u00f3n, promoci\u00f3n e innovaci\u00f3n de sus dise\u00f1os. El proyecto busca posicionar la artesan\u00eda como un icono del Departamento de Misiones y llevarla m\u00e1s all\u00e1 de sus confines.<\/p>\n\n\n\n<p>El objetivo es desarrollar un plan de arte y dise\u00f1o que vincule a Bellas Artes con el sector artesanal paraguayo para fortalecer la investigaci\u00f3n, innovaci\u00f3n y producci\u00f3n sostenible, preservando los saberes tradicionales y combin\u00e1ndolos con tecnolog\u00eda. Adem\u00e1s, la formaci\u00f3n de nuevas generaciones, la mejora de la gesti\u00f3n y comercializaci\u00f3n, promoviendo la econom\u00eda circular y fortaleciendo las capacidades institucionales del ISBA.<\/p>\n\n\n\n<p><a href=\"https:\/\/bellasartes.edu.py\/index.php\/noticias-isba\/\">M\u00e1s Noticias<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre hilos, retazos de tejidos y recuerdos, un grupo de mujeres de Santa Mar\u00eda de Fe, departamento de Misiones, mantiene viva una tradici\u00f3n artesanal nacida hace m\u00e1s de cuatro d\u00e9cadas. En el Taller de la Hermandad las artesanas bordan sus historias y realidades, con coloridas figuras hechas con retazos de tela, que forman personajes y [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5901,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"fifu_image_url":"http:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0425-scaled.jpg","fifu_image_alt":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-5892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Taller de la Hermandad: una artesan\u00eda textil con historia<\/title>\n<meta name=\"description\" content=\"Bellas Artes esta encabezando un proyecto con el Taller de la Hermandad para la conservaci\u00f3n, promoci\u00f3n e innovaci\u00f3n de sus dise\u00f1os.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bellasartes.edu.py\/index.php\/2025\/11\/07\/taller-de-la-hermandad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Taller de la Hermandad: una artesan\u00eda textil con historia\" \/>\n<meta property=\"og:description\" content=\"Bellas Artes esta encabezando un proyecto con el Taller de la Hermandad para la conservaci\u00f3n, promoci\u00f3n e innovaci\u00f3n de sus dise\u00f1os.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bellasartes.edu.py\/index.php\/2025\/11\/07\/taller-de-la-hermandad\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto Superior de Bellas Artes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/isbaoficial\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-07T12:25:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-07T12:25:33+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0425-scaled.jpg\" \/>\n<meta name=\"author\" content=\"comunicarte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"http:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0425-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicarte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2025\\\/11\\\/07\\\/taller-de-la-hermandad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2025\\\/11\\\/07\\\/taller-de-la-hermandad\\\/\"},\"author\":{\"name\":\"comunicarte\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#\\\/schema\\\/person\\\/6243d56ea2e518f0b57594d7a454e37a\"},\"headline\":\"Taller de la Hermandad: una artesan\u00eda textil con historia que Bellas Artes desea intervenir\",\"datePublished\":\"2025-11-07T12:25:29+00:00\",\"dateModified\":\"2025-11-07T12:25:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2025\\\/11\\\/07\\\/taller-de-la-hermandad\\\/\"},\"wordCount\":706,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2025\\\/11\\\/07\\\/taller-de-la-hermandad\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/bellasartes.edu.py\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG_0425-scaled.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2025\\\/11\\\/07\\\/taller-de-la-hermandad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2025\\\/11\\\/07\\\/taller-de-la-hermandad\\\/\",\"url\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2025\\\/11\\\/07\\\/taller-de-la-hermandad\\\/\",\"name\":\"Taller de la Hermandad: una artesan\u00eda textil con historia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2025\\\/11\\\/07\\\/taller-de-la-hermandad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2025\\\/11\\\/07\\\/taller-de-la-hermandad\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/bellasartes.edu.py\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG_0425-scaled.jpg\",\"datePublished\":\"2025-11-07T12:25:29+00:00\",\"dateModified\":\"2025-11-07T12:25:33+00:00\",\"description\":\"Bellas Artes esta encabezando un proyecto con el Taller de la Hermandad para la conservaci\u00f3n, promoci\u00f3n e innovaci\u00f3n de sus dise\u00f1os.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2025\\\/11\\\/07\\\/taller-de-la-hermandad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2025\\\/11\\\/07\\\/taller-de-la-hermandad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2025\\\/11\\\/07\\\/taller-de-la-hermandad\\\/#primaryimage\",\"url\":\"http:\\\/\\\/bellasartes.edu.py\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG_0425-scaled.jpg\",\"contentUrl\":\"http:\\\/\\\/bellasartes.edu.py\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG_0425-scaled.jpg\",\"width\":\"2560\",\"height\":\"1707\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2025\\\/11\\\/07\\\/taller-de-la-hermandad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bellasartes.edu.py\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Taller de la Hermandad: una artesan\u00eda textil con historia que Bellas Artes desea intervenir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#website\",\"url\":\"https:\\\/\\\/bellasartes.edu.py\\\/\",\"name\":\"Instituto Superior de Bellas Artes\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bellasartes.edu.py\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#organization\",\"name\":\"Instituto Superior de Bellas Artes\",\"url\":\"https:\\\/\\\/bellasartes.edu.py\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bellasartes.edu.py\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-imagenes-y-logos_Mesa-de-trabajo-1.png\",\"contentUrl\":\"https:\\\/\\\/bellasartes.edu.py\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-imagenes-y-logos_Mesa-de-trabajo-1.png\",\"width\":512,\"height\":512,\"caption\":\"Instituto Superior de Bellas Artes\"},\"image\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/isbaoficial\",\"https:\\\/\\\/www.instagram.com\\\/bellasartes.py\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/74351323\\\/admin\\\/feed\\\/posts\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#\\\/schema\\\/person\\\/6243d56ea2e518f0b57594d7a454e37a\",\"name\":\"comunicarte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73b4d6769843e544de958c36b6a5ccd5fbfbe514a048340133a4d304a2f5777b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73b4d6769843e544de958c36b6a5ccd5fbfbe514a048340133a4d304a2f5777b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73b4d6769843e544de958c36b6a5ccd5fbfbe514a048340133a4d304a2f5777b?s=96&d=mm&r=g\",\"caption\":\"comunicarte\"},\"url\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/author\\\/comunicarte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Taller de la Hermandad: una artesan\u00eda textil con historia","description":"Bellas Artes esta encabezando un proyecto con el Taller de la Hermandad para la conservaci\u00f3n, promoci\u00f3n e innovaci\u00f3n de sus dise\u00f1os.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bellasartes.edu.py\/index.php\/2025\/11\/07\/taller-de-la-hermandad\/","og_locale":"es_ES","og_type":"article","og_title":"Taller de la Hermandad: una artesan\u00eda textil con historia","og_description":"Bellas Artes esta encabezando un proyecto con el Taller de la Hermandad para la conservaci\u00f3n, promoci\u00f3n e innovaci\u00f3n de sus dise\u00f1os.","og_url":"https:\/\/bellasartes.edu.py\/index.php\/2025\/11\/07\/taller-de-la-hermandad\/","og_site_name":"Instituto Superior de Bellas Artes","article_publisher":"https:\/\/www.facebook.com\/isbaoficial","article_published_time":"2025-11-07T12:25:29+00:00","article_modified_time":"2025-11-07T12:25:33+00:00","og_image":[{"url":"http:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0425-scaled.jpg","type":"","width":"","height":""}],"author":"comunicarte","twitter_card":"summary_large_image","twitter_image":"http:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0425-scaled.jpg","twitter_misc":{"Escrito por":"comunicarte","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bellasartes.edu.py\/index.php\/2025\/11\/07\/taller-de-la-hermandad\/#article","isPartOf":{"@id":"https:\/\/bellasartes.edu.py\/index.php\/2025\/11\/07\/taller-de-la-hermandad\/"},"author":{"name":"comunicarte","@id":"https:\/\/bellasartes.edu.py\/#\/schema\/person\/6243d56ea2e518f0b57594d7a454e37a"},"headline":"Taller de la Hermandad: una artesan\u00eda textil con historia que Bellas Artes desea intervenir","datePublished":"2025-11-07T12:25:29+00:00","dateModified":"2025-11-07T12:25:33+00:00","mainEntityOfPage":{"@id":"https:\/\/bellasartes.edu.py\/index.php\/2025\/11\/07\/taller-de-la-hermandad\/"},"wordCount":706,"commentCount":0,"publisher":{"@id":"https:\/\/bellasartes.edu.py\/#organization"},"image":{"@id":"https:\/\/bellasartes.edu.py\/index.php\/2025\/11\/07\/taller-de-la-hermandad\/#primaryimage"},"thumbnailUrl":"http:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0425-scaled.jpg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bellasartes.edu.py\/index.php\/2025\/11\/07\/taller-de-la-hermandad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bellasartes.edu.py\/index.php\/2025\/11\/07\/taller-de-la-hermandad\/","url":"https:\/\/bellasartes.edu.py\/index.php\/2025\/11\/07\/taller-de-la-hermandad\/","name":"Taller de la Hermandad: una artesan\u00eda textil con historia","isPartOf":{"@id":"https:\/\/bellasartes.edu.py\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bellasartes.edu.py\/index.php\/2025\/11\/07\/taller-de-la-hermandad\/#primaryimage"},"image":{"@id":"https:\/\/bellasartes.edu.py\/index.php\/2025\/11\/07\/taller-de-la-hermandad\/#primaryimage"},"thumbnailUrl":"http:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0425-scaled.jpg","datePublished":"2025-11-07T12:25:29+00:00","dateModified":"2025-11-07T12:25:33+00:00","description":"Bellas Artes esta encabezando un proyecto con el Taller de la Hermandad para la conservaci\u00f3n, promoci\u00f3n e innovaci\u00f3n de sus dise\u00f1os.","breadcrumb":{"@id":"https:\/\/bellasartes.edu.py\/index.php\/2025\/11\/07\/taller-de-la-hermandad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bellasartes.edu.py\/index.php\/2025\/11\/07\/taller-de-la-hermandad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bellasartes.edu.py\/index.php\/2025\/11\/07\/taller-de-la-hermandad\/#primaryimage","url":"http:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0425-scaled.jpg","contentUrl":"http:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0425-scaled.jpg","width":"2560","height":"1707"},{"@type":"BreadcrumbList","@id":"https:\/\/bellasartes.edu.py\/index.php\/2025\/11\/07\/taller-de-la-hermandad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bellasartes.edu.py\/"},{"@type":"ListItem","position":2,"name":"Taller de la Hermandad: una artesan\u00eda textil con historia que Bellas Artes desea intervenir"}]},{"@type":"WebSite","@id":"https:\/\/bellasartes.edu.py\/#website","url":"https:\/\/bellasartes.edu.py\/","name":"Instituto Superior de Bellas Artes","description":"","publisher":{"@id":"https:\/\/bellasartes.edu.py\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bellasartes.edu.py\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/bellasartes.edu.py\/#organization","name":"Instituto Superior de Bellas Artes","url":"https:\/\/bellasartes.edu.py\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bellasartes.edu.py\/#\/schema\/logo\/image\/","url":"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2024\/03\/cropped-imagenes-y-logos_Mesa-de-trabajo-1.png","contentUrl":"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2024\/03\/cropped-imagenes-y-logos_Mesa-de-trabajo-1.png","width":512,"height":512,"caption":"Instituto Superior de Bellas Artes"},"image":{"@id":"https:\/\/bellasartes.edu.py\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/isbaoficial","https:\/\/www.instagram.com\/bellasartes.py\/","https:\/\/www.linkedin.com\/school\/74351323\/admin\/feed\/posts\/"]},{"@type":"Person","@id":"https:\/\/bellasartes.edu.py\/#\/schema\/person\/6243d56ea2e518f0b57594d7a454e37a","name":"comunicarte","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/73b4d6769843e544de958c36b6a5ccd5fbfbe514a048340133a4d304a2f5777b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/73b4d6769843e544de958c36b6a5ccd5fbfbe514a048340133a4d304a2f5777b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/73b4d6769843e544de958c36b6a5ccd5fbfbe514a048340133a4d304a2f5777b?s=96&d=mm&r=g","caption":"comunicarte"},"url":"https:\/\/bellasartes.edu.py\/index.php\/author\/comunicarte\/"}]}},"jetpack_featured_media_url":"http:\/\/bellasartes.edu.py\/wp-content\/uploads\/2025\/11\/IMG_0425-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/posts\/5892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/comments?post=5892"}],"version-history":[{"count":1,"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/posts\/5892\/revisions"}],"predecessor-version":[{"id":5900,"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/posts\/5892\/revisions\/5900"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/media\/5901"}],"wp:attachment":[{"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/media?parent=5892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/categories?post=5892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/tags?post=5892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}