{"id":6882,"date":"2026-05-11T17:58:24","date_gmt":"2026-05-11T17:58:24","guid":{"rendered":"https:\/\/bellasartes.edu.py\/?p=6882"},"modified":"2026-05-11T18:39:48","modified_gmt":"2026-05-11T18:39:48","slug":"estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias","status":"publish","type":"post","link":"https:\/\/bellasartes.edu.py\/index.php\/2026\/05\/11\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\/","title":{"rendered":"Estudiantes de Bellas Artes llevan arte a las Fiestas Patrias"},"content":{"rendered":"\n<p>En el marco de las fiestas patrias en homenaje a la Independencia del Paraguay, los estudiantes del Instituto Superior de Bellas Artes participar\u00e1n en distintas actividades art\u00edsticas y de extensi\u00f3n organizadas junto con instituciones educativas y la Secretar\u00eda Nacional de Cultura (SNC).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Teatro \u00d1omongueta en la Escuela Manuel Ortiz Guerrero<\/strong><\/h2>\n\n\n\n<p>El mi\u00e9rcoles 13 de mayo, estudiantes de la carrera de Arte Dram\u00e1tico visitar\u00e1n la Escuela Manuel Ortiz Guerrero como parte de la agenda del proyecto <strong>\u201cTeatro \u00d1omongueta\u201d<\/strong>, realizando representaciones de personajes hist\u00f3ricos y pr\u00f3ceres como Mauricio Jos\u00e9 Troche y Juana de Lara.<\/p>\n\n\n\n<p>La actividad, que contar\u00e1 con el acompa\u00f1amiento de la directora acad\u00e9mica, busca acercar el teatro y la historia de nuestro pa\u00eds a la comunidad educativa, fomentando la identidad cultural y el valor de las fechas patrias a trav\u00e9s de las artes esc\u00e9nicas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>T\u00edteres en la Manzana de la Rivera<\/strong><\/h2>\n\n\n\n<p>Por otra parte, el jueves 14 de mayo, estudiantes del segundo a\u00f1o participar\u00e1n en una presentaci\u00f3n de t\u00edteres en el Centro Cultural Manzana de la Rivera, como actividad de extensi\u00f3n dirigida por el profesor <strong>Mario To\u00f1anez<\/strong>, desde la c\u00e1tedra de T\u00edteres.<\/p>\n\n\n\n<p>Durante la presentaci\u00f3n se representar\u00e1n reconocidos personajes hist\u00f3ricos interpretados por estudiantes del ISBA:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Carlos Colombino &#8211; Milagros Villasboa<\/li>\n\n\n\n<li>Domingo Mart\u00ednez de Irala &#8211; Samira Rivarola<\/li>\n\n\n\n<li>Miguel Acevedo &#8211; Yamil Maidana<\/li>\n\n\n\n<li>Federico Garc\u00eda Lorca &#8211; Ana Paula D\u00edaz<\/li>\n\n\n\n<li>Augusto Roa Bastos &#8211; Sof\u00eda Acosta<\/li>\n<\/ul>\n\n\n\n<p>La propuesta busca revalorizar figuras emblem\u00e1ticas de la cultura y la historia con el lenguaje teatral y el arte de los t\u00edteres.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Bellas Artes se suma a \u201cRumores 1811\u201d<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"771\" height=\"1024\" data-id=\"6884\" src=\"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2026\/05\/Rumores-1811-2025-7-771x1024.jpeg\" alt=\"\" class=\"wp-image-6884\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"771\" height=\"1024\" data-id=\"6886\" src=\"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2026\/05\/Rumores-1811-2025-8-771x1024.jpeg\" alt=\"\" class=\"wp-image-6886\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"771\" height=\"1024\" data-id=\"6885\" src=\"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2026\/05\/Rumores-1811-2025-6-771x1024.jpeg\" alt=\"\" class=\"wp-image-6885\"\/><\/figure>\n<\/figure>\n\n\n\n<p>Adem\u00e1s, el ISBA participar\u00e1 en el evento <strong>\u201cRumores 1811\u201d<\/strong>, organizado junto a la Secretar\u00eda Nacional de Cultura, dentro de los festejos patrios previstos para los d\u00edas 14 y 15 de mayo.<\/p>\n\n\n\n<p>Las actividades se desarrollar\u00e1n el jueves 14 de mayo, de 17:00 a 23:00 horas, y forman parte de una puesta art\u00edstica donde estudiantes del instituto representar\u00e1n roles caracter\u00edsticos de la \u00e9poca independentista, entre ellos: pregoneros, tamborileros, vendedores, pulperos, lavanderas, herreros, zapateros y personajes del pueblo.<\/p>\n\n\n\n<p>La Direcci\u00f3n de Extensi\u00f3n, lleva esta iniciativa como parte del trabajo junto con la SNC, para promover la participaci\u00f3n estudiantil en espacios culturales de gran relevancia para la memoria hist\u00f3rica y la identidad nacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de las fiestas patrias en homenaje a la Independencia del Paraguay, los estudiantes del Instituto Superior de Bellas Artes participar\u00e1n en distintas actividades art\u00edsticas y de extensi\u00f3n organizadas junto con instituciones educativas y la Secretar\u00eda Nacional de Cultura (SNC). Teatro \u00d1omongueta en la Escuela Manuel Ortiz Guerrero El mi\u00e9rcoles 13 de mayo, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6888,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"fifu_image_url":"http:\/\/bellasartes.edu.py\/wp-content\/uploads\/2026\/05\/Rumores-1811-2025-11.jpeg","fifu_image_alt":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-6882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estudiantes de Bellas Artes llevan arte a las Fiestas Patrias<\/title>\n<meta name=\"description\" content=\"En el marco de las fiestas patrias, los estudiantes de Bellas Artes participar\u00e1n en distintas actividades art\u00edsticas y de extensi\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bellasartes.edu.py\/index.php\/2026\/05\/11\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudiantes de Bellas Artes llevan arte a las Fiestas Patrias\" \/>\n<meta property=\"og:description\" content=\"En el marco de las fiestas patrias, los estudiantes de Bellas Artes participar\u00e1n en distintas actividades art\u00edsticas y de extensi\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bellasartes.edu.py\/index.php\/2026\/05\/11\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto Superior de Bellas Artes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/isbaoficial\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T17:58:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T18:39:48+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/bellasartes.edu.py\/wp-content\/uploads\/2026\/05\/Rumores-1811-2025-11.jpeg\" \/>\n<meta name=\"author\" content=\"comunicarte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"http:\/\/bellasartes.edu.py\/wp-content\/uploads\/2026\/05\/Rumores-1811-2025-11.jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicarte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2026\\\/05\\\/11\\\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2026\\\/05\\\/11\\\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\\\/\"},\"author\":{\"name\":\"comunicarte\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#\\\/schema\\\/person\\\/6243d56ea2e518f0b57594d7a454e37a\"},\"headline\":\"Estudiantes de Bellas Artes llevan arte a las Fiestas Patrias\",\"datePublished\":\"2026-05-11T17:58:24+00:00\",\"dateModified\":\"2026-05-11T18:39:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2026\\\/05\\\/11\\\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\\\/\"},\"wordCount\":408,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2026\\\/05\\\/11\\\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/bellasartes.edu.py\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Rumores-1811-2025-11.jpeg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2026\\\/05\\\/11\\\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2026\\\/05\\\/11\\\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\\\/\",\"url\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2026\\\/05\\\/11\\\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\\\/\",\"name\":\"Estudiantes de Bellas Artes llevan arte a las Fiestas Patrias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2026\\\/05\\\/11\\\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2026\\\/05\\\/11\\\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/bellasartes.edu.py\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Rumores-1811-2025-11.jpeg\",\"datePublished\":\"2026-05-11T17:58:24+00:00\",\"dateModified\":\"2026-05-11T18:39:48+00:00\",\"description\":\"En el marco de las fiestas patrias, los estudiantes de Bellas Artes participar\u00e1n en distintas actividades art\u00edsticas y de extensi\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2026\\\/05\\\/11\\\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2026\\\/05\\\/11\\\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2026\\\/05\\\/11\\\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\\\/#primaryimage\",\"url\":\"http:\\\/\\\/bellasartes.edu.py\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Rumores-1811-2025-11.jpeg\",\"contentUrl\":\"http:\\\/\\\/bellasartes.edu.py\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Rumores-1811-2025-11.jpeg\",\"width\":\"1600\",\"height\":\"1204\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/2026\\\/05\\\/11\\\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bellasartes.edu.py\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudiantes de Bellas Artes llevan arte a las Fiestas Patrias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#website\",\"url\":\"https:\\\/\\\/bellasartes.edu.py\\\/\",\"name\":\"Instituto Superior de Bellas Artes\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bellasartes.edu.py\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#organization\",\"name\":\"Instituto Superior de Bellas Artes\",\"url\":\"https:\\\/\\\/bellasartes.edu.py\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bellasartes.edu.py\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-imagenes-y-logos_Mesa-de-trabajo-1.png\",\"contentUrl\":\"https:\\\/\\\/bellasartes.edu.py\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-imagenes-y-logos_Mesa-de-trabajo-1.png\",\"width\":512,\"height\":512,\"caption\":\"Instituto Superior de Bellas Artes\"},\"image\":{\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/isbaoficial\",\"https:\\\/\\\/www.instagram.com\\\/bellasartes.py\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/74351323\\\/admin\\\/feed\\\/posts\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bellasartes.edu.py\\\/#\\\/schema\\\/person\\\/6243d56ea2e518f0b57594d7a454e37a\",\"name\":\"comunicarte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73b4d6769843e544de958c36b6a5ccd5fbfbe514a048340133a4d304a2f5777b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73b4d6769843e544de958c36b6a5ccd5fbfbe514a048340133a4d304a2f5777b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/73b4d6769843e544de958c36b6a5ccd5fbfbe514a048340133a4d304a2f5777b?s=96&d=mm&r=g\",\"caption\":\"comunicarte\"},\"url\":\"https:\\\/\\\/bellasartes.edu.py\\\/index.php\\\/author\\\/comunicarte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudiantes de Bellas Artes llevan arte a las Fiestas Patrias","description":"En el marco de las fiestas patrias, los estudiantes de Bellas Artes participar\u00e1n en distintas actividades art\u00edsticas y de extensi\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bellasartes.edu.py\/index.php\/2026\/05\/11\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\/","og_locale":"es_ES","og_type":"article","og_title":"Estudiantes de Bellas Artes llevan arte a las Fiestas Patrias","og_description":"En el marco de las fiestas patrias, los estudiantes de Bellas Artes participar\u00e1n en distintas actividades art\u00edsticas y de extensi\u00f3n.","og_url":"https:\/\/bellasartes.edu.py\/index.php\/2026\/05\/11\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\/","og_site_name":"Instituto Superior de Bellas Artes","article_publisher":"https:\/\/www.facebook.com\/isbaoficial","article_published_time":"2026-05-11T17:58:24+00:00","article_modified_time":"2026-05-11T18:39:48+00:00","og_image":[{"url":"http:\/\/bellasartes.edu.py\/wp-content\/uploads\/2026\/05\/Rumores-1811-2025-11.jpeg","type":"","width":"","height":""}],"author":"comunicarte","twitter_card":"summary_large_image","twitter_image":"http:\/\/bellasartes.edu.py\/wp-content\/uploads\/2026\/05\/Rumores-1811-2025-11.jpeg","twitter_misc":{"Escrito por":"comunicarte","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bellasartes.edu.py\/index.php\/2026\/05\/11\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\/#article","isPartOf":{"@id":"https:\/\/bellasartes.edu.py\/index.php\/2026\/05\/11\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\/"},"author":{"name":"comunicarte","@id":"https:\/\/bellasartes.edu.py\/#\/schema\/person\/6243d56ea2e518f0b57594d7a454e37a"},"headline":"Estudiantes de Bellas Artes llevan arte a las Fiestas Patrias","datePublished":"2026-05-11T17:58:24+00:00","dateModified":"2026-05-11T18:39:48+00:00","mainEntityOfPage":{"@id":"https:\/\/bellasartes.edu.py\/index.php\/2026\/05\/11\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\/"},"wordCount":408,"commentCount":0,"publisher":{"@id":"https:\/\/bellasartes.edu.py\/#organization"},"image":{"@id":"https:\/\/bellasartes.edu.py\/index.php\/2026\/05\/11\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\/#primaryimage"},"thumbnailUrl":"http:\/\/bellasartes.edu.py\/wp-content\/uploads\/2026\/05\/Rumores-1811-2025-11.jpeg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bellasartes.edu.py\/index.php\/2026\/05\/11\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bellasartes.edu.py\/index.php\/2026\/05\/11\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\/","url":"https:\/\/bellasartes.edu.py\/index.php\/2026\/05\/11\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\/","name":"Estudiantes de Bellas Artes llevan arte a las Fiestas Patrias","isPartOf":{"@id":"https:\/\/bellasartes.edu.py\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bellasartes.edu.py\/index.php\/2026\/05\/11\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\/#primaryimage"},"image":{"@id":"https:\/\/bellasartes.edu.py\/index.php\/2026\/05\/11\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\/#primaryimage"},"thumbnailUrl":"http:\/\/bellasartes.edu.py\/wp-content\/uploads\/2026\/05\/Rumores-1811-2025-11.jpeg","datePublished":"2026-05-11T17:58:24+00:00","dateModified":"2026-05-11T18:39:48+00:00","description":"En el marco de las fiestas patrias, los estudiantes de Bellas Artes participar\u00e1n en distintas actividades art\u00edsticas y de extensi\u00f3n.","breadcrumb":{"@id":"https:\/\/bellasartes.edu.py\/index.php\/2026\/05\/11\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bellasartes.edu.py\/index.php\/2026\/05\/11\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bellasartes.edu.py\/index.php\/2026\/05\/11\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\/#primaryimage","url":"http:\/\/bellasartes.edu.py\/wp-content\/uploads\/2026\/05\/Rumores-1811-2025-11.jpeg","contentUrl":"http:\/\/bellasartes.edu.py\/wp-content\/uploads\/2026\/05\/Rumores-1811-2025-11.jpeg","width":"1600","height":"1204"},{"@type":"BreadcrumbList","@id":"https:\/\/bellasartes.edu.py\/index.php\/2026\/05\/11\/estudiantes-de-bellas-artes-llevan-arte-a-las-fiestas-patrias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bellasartes.edu.py\/"},{"@type":"ListItem","position":2,"name":"Estudiantes de Bellas Artes llevan arte a las Fiestas Patrias"}]},{"@type":"WebSite","@id":"https:\/\/bellasartes.edu.py\/#website","url":"https:\/\/bellasartes.edu.py\/","name":"Instituto Superior de Bellas Artes","description":"","publisher":{"@id":"https:\/\/bellasartes.edu.py\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bellasartes.edu.py\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/bellasartes.edu.py\/#organization","name":"Instituto Superior de Bellas Artes","url":"https:\/\/bellasartes.edu.py\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bellasartes.edu.py\/#\/schema\/logo\/image\/","url":"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2024\/03\/cropped-imagenes-y-logos_Mesa-de-trabajo-1.png","contentUrl":"https:\/\/bellasartes.edu.py\/wp-content\/uploads\/2024\/03\/cropped-imagenes-y-logos_Mesa-de-trabajo-1.png","width":512,"height":512,"caption":"Instituto Superior de Bellas Artes"},"image":{"@id":"https:\/\/bellasartes.edu.py\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/isbaoficial","https:\/\/www.instagram.com\/bellasartes.py\/","https:\/\/www.linkedin.com\/school\/74351323\/admin\/feed\/posts\/"]},{"@type":"Person","@id":"https:\/\/bellasartes.edu.py\/#\/schema\/person\/6243d56ea2e518f0b57594d7a454e37a","name":"comunicarte","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/73b4d6769843e544de958c36b6a5ccd5fbfbe514a048340133a4d304a2f5777b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/73b4d6769843e544de958c36b6a5ccd5fbfbe514a048340133a4d304a2f5777b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/73b4d6769843e544de958c36b6a5ccd5fbfbe514a048340133a4d304a2f5777b?s=96&d=mm&r=g","caption":"comunicarte"},"url":"https:\/\/bellasartes.edu.py\/index.php\/author\/comunicarte\/"}]}},"jetpack_featured_media_url":"http:\/\/bellasartes.edu.py\/wp-content\/uploads\/2026\/05\/Rumores-1811-2025-11.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/posts\/6882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/comments?post=6882"}],"version-history":[{"count":1,"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/posts\/6882\/revisions"}],"predecessor-version":[{"id":6887,"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/posts\/6882\/revisions\/6887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/media\/6888"}],"wp:attachment":[{"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/media?parent=6882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/categories?post=6882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bellasartes.edu.py\/index.php\/wp-json\/wp\/v2\/tags?post=6882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}